{"id":946132,"date":"2024-08-21T19:37:33","date_gmt":"2024-08-21T19:37:33","guid":{"rendered":"https:\/\/talkpal.ai\/verb\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/"},"modified":"2024-08-21T19:37:33","modified_gmt":"2024-08-21T19:37:33","slug":"ergeben-explicacao-frases-de-exemplo-e-conjugacao","status":"publish","type":"verb","link":"https:\/\/talkpal.ai\/pt-pt\/dictionary\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/","title":{"rendered":"Ergeben"},"content":{"rendered":"","protected":false},"featured_media":1527634,"template":"","dictionary_language":[4301],"class_list":["post-946132","verb","type-verb","status-publish","has-post-thumbnail","hentry","dictionary_language-alemao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ergeben - Explica\u00e7\u00e3o, frases de exemplo e conjuga\u00e7\u00e3o - Talkpal<\/title>\n<meta name=\"description\" content=\"O verbo &quot;ergeben&quot; em alem\u00e3o \u00e9 um verbo interessante e multifacetado que pode ter v\u00e1rias interpreta\u00e7\u00f5es dependendo do contexto em que \u00e9 utilizado. De uma forma geral, &quot;ergeben&quot; pode significar &quot;resultar em&quot;, &quot;render-se&quot;, &quot;dedicar-se&quot; ou &quot;mostrar&quot;, entre outros significados. Esta versatilidade torna-o um verbo bastante \u00fatil e comum na l\u00edngua alem\u00e3. No sentido de &quot;resultar em&quot;, &quot;ergeben&quot; \u00e9 frequentemente utilizado para descrever o resultado ou a consequ\u00eancia de uma situa\u00e7\u00e3o ou a\u00e7\u00e3o. Por exemplo, pode ser usado para indicar o que algo &quot;produz&quot; ou &quot;gera&quot;. Quando usado no sentido de &quot;render-se&quot;, &quot;ergeben&quot; pode significar submeter-se ou entregar-se, frequentemente em contextos militares ou de conflito, mas tamb\u00e9m em situa\u00e7\u00f5es mais figurativas, como aceitar uma situa\u00e7\u00e3o inevit\u00e1vel. Al\u00e9m disso, &quot;ergeben&quot; pode tamb\u00e9m significar &quot;dedicar-se&quot; ou &quot;ser devoto a algo ou algu\u00e9m&quot;, indicando lealdade ou compromisso. Por fim, &quot;ergeben&quot; pode ser utilizado para indicar a revela\u00e7\u00e3o de algo, como fatos ou verdades que se tornam evidentes. Esta variedade de significados faz do verbo &quot;ergeben&quot; uma palavra rica e complexa, cuja compreens\u00e3o e uso correto podem enriquecer bastante o dom\u00ednio da l\u00edngua alem\u00e3 para falantes de portugu\u00eas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/talkpal.ai\/pt-pt\/dictionary\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ergeben - Explica\u00e7\u00e3o, frases de exemplo e conjuga\u00e7\u00e3o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/talkpal.ai\/pt-pt\/dictionary\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Talkpal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100090733639311\" \/>\n<meta property=\"og:image\" content=\"https:\/\/talkpal.ai\/wp-content\/uploads\/2024\/05\/Notification_img_10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@talkpalai\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/dictionary\\\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\\\/\",\"url\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/dictionary\\\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\\\/\",\"name\":\"Ergeben - Explica\u00e7\u00e3o, frases de exemplo e conjuga\u00e7\u00e3o - Talkpal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/dictionary\\\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/dictionary\\\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/talkpal.ai\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/digital-lessons-help-to-learn-languages.webp\",\"datePublished\":\"2024-08-21T19:37:33+00:00\",\"description\":\"O verbo \\\"ergeben\\\" em alem\u00e3o \u00e9 um verbo interessante e multifacetado que pode ter v\u00e1rias interpreta\u00e7\u00f5es dependendo do contexto em que \u00e9 utilizado. De uma forma geral, \\\"ergeben\\\" pode significar \\\"resultar em\\\", \\\"render-se\\\", \\\"dedicar-se\\\" ou \\\"mostrar\\\", entre outros significados. Esta versatilidade torna-o um verbo bastante \u00fatil e comum na l\u00edngua alem\u00e3. No sentido de \\\"resultar em\\\", \\\"ergeben\\\" \u00e9 frequentemente utilizado para descrever o resultado ou a consequ\u00eancia de uma situa\u00e7\u00e3o ou a\u00e7\u00e3o. Por exemplo, pode ser usado para indicar o que algo \\\"produz\\\" ou \\\"gera\\\". Quando usado no sentido de \\\"render-se\\\", \\\"ergeben\\\" pode significar submeter-se ou entregar-se, frequentemente em contextos militares ou de conflito, mas tamb\u00e9m em situa\u00e7\u00f5es mais figurativas, como aceitar uma situa\u00e7\u00e3o inevit\u00e1vel. Al\u00e9m disso, \\\"ergeben\\\" pode tamb\u00e9m significar \\\"dedicar-se\\\" ou \\\"ser devoto a algo ou algu\u00e9m\\\", indicando lealdade ou compromisso. Por fim, \\\"ergeben\\\" pode ser utilizado para indicar a revela\u00e7\u00e3o de algo, como fatos ou verdades que se tornam evidentes. Esta variedade de significados faz do verbo \\\"ergeben\\\" uma palavra rica e complexa, cuja compreens\u00e3o e uso correto podem enriquecer bastante o dom\u00ednio da l\u00edngua alem\u00e3 para falantes de portugu\u00eas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/dictionary\\\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/dictionary\\\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/dictionary\\\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/talkpal.ai\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/digital-lessons-help-to-learn-languages.webp\",\"contentUrl\":\"https:\\\/\\\/talkpal.ai\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/digital-lessons-help-to-learn-languages.webp\",\"width\":1200,\"height\":896,\"caption\":\"Diverse students use laptops and textbooks while learning languages in a large, brightly lit study hall.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/dictionary\\\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dicion\u00e1rio de Alem\u00e3o\",\"item\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/dictionary_language\\\/alemao\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ergeben &#8211; Explica\u00e7\u00e3o, frases de exemplo e conjuga\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/\",\"name\":\"Talkpal\",\"description\":\"AI Language Learning\",\"publisher\":{\"@id\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/#organization\"},\"alternateName\":\"Talkpal AI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/#organization\",\"name\":\"Talkpal, Inc.\",\"alternateName\":\"Talkpal AI\",\"url\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/talkpal.ai\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Talkpal-Logo-Icon.png\",\"contentUrl\":\"https:\\\/\\\/talkpal.ai\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Talkpal-Logo-Icon.png\",\"width\":2880,\"height\":2880,\"caption\":\"Talkpal, Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/talkpal.ai\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100090733639311\",\"https:\\\/\\\/x.com\\\/talkpalai\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/talkpal\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@TalkPal\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@talkpal\",\"https:\\\/\\\/www.instagram.com\\\/talkpal_ai\\\/\",\"https:\\\/\\\/www.crunchbase.com\\\/organization\\\/talkpal-9cde\",\"https:\\\/\\\/www.g2.com\\\/products\\\/talkpal-for-business\\\/\",\"https:\\\/\\\/www.trustpilot.com\\\/review\\\/talkpal.ai\",\"https:\\\/\\\/www.capterra.com\\\/p\\\/10006800\\\/TalkPal\\\/\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Talkpal_AI\"],\"description\":\"Talkpal is a language learning web and mobile education app, powered by the latest AI technologies, that provides engaging experiences to its customers in many different languages to help them improve their language skills. Users can chat about unlimited amount of topics with the app and use other modes to practice their language learning.\",\"email\":\"support@talkpal.ai\",\"legalName\":\"Talkpal, Inc.\",\"foundingDate\":\"2023-04-03\",\"duns\":\"118989042\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/talkpal.ai\\\/publishing-principles\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/talkpal.ai\\\/actionable-feedback-policy\\\/\",\"correctionsPolicy\":\"https:\\\/\\\/talkpal.ai\\\/corrections-policy\\\/\",\"ethicsPolicy\":\"https:\\\/\\\/talkpal.ai\\\/ethics-policy\\\/\",\"diversityPolicy\":\"https:\\\/\\\/talkpal.ai\\\/diversity-policy\\\/\",\"diversityStaffingReport\":\"https:\\\/\\\/talkpal.ai\\\/diversity-policy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ergeben - Explica\u00e7\u00e3o, frases de exemplo e conjuga\u00e7\u00e3o - Talkpal","description":"O verbo \"ergeben\" em alem\u00e3o \u00e9 um verbo interessante e multifacetado que pode ter v\u00e1rias interpreta\u00e7\u00f5es dependendo do contexto em que \u00e9 utilizado. De uma forma geral, \"ergeben\" pode significar \"resultar em\", \"render-se\", \"dedicar-se\" ou \"mostrar\", entre outros significados. Esta versatilidade torna-o um verbo bastante \u00fatil e comum na l\u00edngua alem\u00e3. No sentido de \"resultar em\", \"ergeben\" \u00e9 frequentemente utilizado para descrever o resultado ou a consequ\u00eancia de uma situa\u00e7\u00e3o ou a\u00e7\u00e3o. Por exemplo, pode ser usado para indicar o que algo \"produz\" ou \"gera\". Quando usado no sentido de \"render-se\", \"ergeben\" pode significar submeter-se ou entregar-se, frequentemente em contextos militares ou de conflito, mas tamb\u00e9m em situa\u00e7\u00f5es mais figurativas, como aceitar uma situa\u00e7\u00e3o inevit\u00e1vel. Al\u00e9m disso, \"ergeben\" pode tamb\u00e9m significar \"dedicar-se\" ou \"ser devoto a algo ou algu\u00e9m\", indicando lealdade ou compromisso. Por fim, \"ergeben\" pode ser utilizado para indicar a revela\u00e7\u00e3o de algo, como fatos ou verdades que se tornam evidentes. Esta variedade de significados faz do verbo \"ergeben\" uma palavra rica e complexa, cuja compreens\u00e3o e uso correto podem enriquecer bastante o dom\u00ednio da l\u00edngua alem\u00e3 para falantes de portugu\u00eas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/talkpal.ai\/pt-pt\/dictionary\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/","og_locale":"pt_PT","og_type":"article","og_title":"Ergeben - Explica\u00e7\u00e3o, frases de exemplo e conjuga\u00e7\u00e3o","og_url":"https:\/\/talkpal.ai\/pt-pt\/dictionary\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/","og_site_name":"Talkpal","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100090733639311","og_image":[{"width":1024,"height":1024,"url":"https:\/\/talkpal.ai\/wp-content\/uploads\/2024\/05\/Notification_img_10.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@talkpalai","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/talkpal.ai\/pt-pt\/dictionary\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/","url":"https:\/\/talkpal.ai\/pt-pt\/dictionary\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/","name":"Ergeben - Explica\u00e7\u00e3o, frases de exemplo e conjuga\u00e7\u00e3o - Talkpal","isPartOf":{"@id":"https:\/\/talkpal.ai\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/talkpal.ai\/pt-pt\/dictionary\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/#primaryimage"},"image":{"@id":"https:\/\/talkpal.ai\/pt-pt\/dictionary\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/#primaryimage"},"thumbnailUrl":"https:\/\/talkpal.ai\/wp-content\/uploads\/2025\/12\/digital-lessons-help-to-learn-languages.webp","datePublished":"2024-08-21T19:37:33+00:00","description":"O verbo \"ergeben\" em alem\u00e3o \u00e9 um verbo interessante e multifacetado que pode ter v\u00e1rias interpreta\u00e7\u00f5es dependendo do contexto em que \u00e9 utilizado. De uma forma geral, \"ergeben\" pode significar \"resultar em\", \"render-se\", \"dedicar-se\" ou \"mostrar\", entre outros significados. Esta versatilidade torna-o um verbo bastante \u00fatil e comum na l\u00edngua alem\u00e3. No sentido de \"resultar em\", \"ergeben\" \u00e9 frequentemente utilizado para descrever o resultado ou a consequ\u00eancia de uma situa\u00e7\u00e3o ou a\u00e7\u00e3o. Por exemplo, pode ser usado para indicar o que algo \"produz\" ou \"gera\". Quando usado no sentido de \"render-se\", \"ergeben\" pode significar submeter-se ou entregar-se, frequentemente em contextos militares ou de conflito, mas tamb\u00e9m em situa\u00e7\u00f5es mais figurativas, como aceitar uma situa\u00e7\u00e3o inevit\u00e1vel. Al\u00e9m disso, \"ergeben\" pode tamb\u00e9m significar \"dedicar-se\" ou \"ser devoto a algo ou algu\u00e9m\", indicando lealdade ou compromisso. Por fim, \"ergeben\" pode ser utilizado para indicar a revela\u00e7\u00e3o de algo, como fatos ou verdades que se tornam evidentes. Esta variedade de significados faz do verbo \"ergeben\" uma palavra rica e complexa, cuja compreens\u00e3o e uso correto podem enriquecer bastante o dom\u00ednio da l\u00edngua alem\u00e3 para falantes de portugu\u00eas.","breadcrumb":{"@id":"https:\/\/talkpal.ai\/pt-pt\/dictionary\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/talkpal.ai\/pt-pt\/dictionary\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/talkpal.ai\/pt-pt\/dictionary\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/#primaryimage","url":"https:\/\/talkpal.ai\/wp-content\/uploads\/2025\/12\/digital-lessons-help-to-learn-languages.webp","contentUrl":"https:\/\/talkpal.ai\/wp-content\/uploads\/2025\/12\/digital-lessons-help-to-learn-languages.webp","width":1200,"height":896,"caption":"Diverse students use laptops and textbooks while learning languages in a large, brightly lit study hall."},{"@type":"BreadcrumbList","@id":"https:\/\/talkpal.ai\/pt-pt\/dictionary\/ergeben-explicacao-frases-de-exemplo-e-conjugacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/talkpal.ai\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Dicion\u00e1rio de Alem\u00e3o","item":"https:\/\/talkpal.ai\/pt-pt\/dictionary_language\/alemao\/"},{"@type":"ListItem","position":3,"name":"Ergeben &#8211; Explica\u00e7\u00e3o, frases de exemplo e conjuga\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/talkpal.ai\/pt-pt\/#website","url":"https:\/\/talkpal.ai\/pt-pt\/","name":"Talkpal","description":"AI Language Learning","publisher":{"@id":"https:\/\/talkpal.ai\/pt-pt\/#organization"},"alternateName":"Talkpal AI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/talkpal.ai\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/talkpal.ai\/pt-pt\/#organization","name":"Talkpal, Inc.","alternateName":"Talkpal AI","url":"https:\/\/talkpal.ai\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/talkpal.ai\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/talkpal.ai\/wp-content\/uploads\/2024\/03\/Talkpal-Logo-Icon.png","contentUrl":"https:\/\/talkpal.ai\/wp-content\/uploads\/2024\/03\/Talkpal-Logo-Icon.png","width":2880,"height":2880,"caption":"Talkpal, Inc."},"image":{"@id":"https:\/\/talkpal.ai\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100090733639311","https:\/\/x.com\/talkpalai","https:\/\/www.linkedin.com\/company\/talkpal\/","https:\/\/www.youtube.com\/@TalkPal\/","https:\/\/www.tiktok.com\/@talkpal","https:\/\/www.instagram.com\/talkpal_ai\/","https:\/\/www.crunchbase.com\/organization\/talkpal-9cde","https:\/\/www.g2.com\/products\/talkpal-for-business\/","https:\/\/www.trustpilot.com\/review\/talkpal.ai","https:\/\/www.capterra.com\/p\/10006800\/TalkPal\/","https:\/\/en.wikipedia.org\/wiki\/Talkpal_AI"],"description":"Talkpal is a language learning web and mobile education app, powered by the latest AI technologies, that provides engaging experiences to its customers in many different languages to help them improve their language skills. Users can chat about unlimited amount of topics with the app and use other modes to practice their language learning.","email":"support@talkpal.ai","legalName":"Talkpal, Inc.","foundingDate":"2023-04-03","duns":"118989042","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/talkpal.ai\/publishing-principles\/","actionableFeedbackPolicy":"https:\/\/talkpal.ai\/actionable-feedback-policy\/","correctionsPolicy":"https:\/\/talkpal.ai\/corrections-policy\/","ethicsPolicy":"https:\/\/talkpal.ai\/ethics-policy\/","diversityPolicy":"https:\/\/talkpal.ai\/diversity-policy\/","diversityStaffingReport":"https:\/\/talkpal.ai\/diversity-policy\/"}]}},"_links":{"self":[{"href":"https:\/\/talkpal.ai\/pt-pt\/wp-json\/wp\/v2\/verb\/946132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/talkpal.ai\/pt-pt\/wp-json\/wp\/v2\/verb"}],"about":[{"href":"https:\/\/talkpal.ai\/pt-pt\/wp-json\/wp\/v2\/types\/verb"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/talkpal.ai\/pt-pt\/wp-json\/wp\/v2\/media\/1527634"}],"wp:attachment":[{"href":"https:\/\/talkpal.ai\/pt-pt\/wp-json\/wp\/v2\/media?parent=946132"}],"wp:term":[{"taxonomy":"dictionary_language","embeddable":true,"href":"https:\/\/talkpal.ai\/pt-pt\/wp-json\/wp\/v2\/dictionary_language?post=946132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}