{"id":10215,"date":"2023-04-06T08:46:42","date_gmt":"2023-04-06T08:46:42","guid":{"rendered":"http:\/\/talkpal.ai\/?post_type=grammar&#038;p=10215"},"modified":"2023-04-22T14:02:47","modified_gmt":"2023-04-22T14:02:47","slug":"maitriser-le-past-progressive-en-anglais-guide-complet","status":"publish","type":"grammar","link":"https:\/\/talkpal.ai\/fr\/grammar\/maitriser-le-past-progressive-en-anglais-guide-complet\/","title":{"rendered":"Ma\u00eetriser le Past Progressive en anglais : Guide complet"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le <a href=\"https:\/\/talkpal.ai\/ar\/grammar\/past-progressive-%d9%81%d9%8a-%d9%82%d9%88%d8%a7%d8%b9%d8%af-%d8%a7%d9%84%d9%84%d8%ba%d8%a9-%d8%a7%d9%84%d8%a5%d9%86%d8%ac%d9%84%d9%8a%d8%b2%d9%8a%d8%a9\/\">Past Progressive<\/a>, \u00e9galement connu sous le nom de \u00ab\u00a0<a href=\"https:\/\/talkpal.ai\/es\/domina-el-past-continuous-guia-facil-y-practica\/\">Past Continuous<\/a>\u00a0\u00bb en <a href=\"https:\/\/talkpal.ai\/learn-english-with-ai\/\">anglais<\/a>, est un <a href=\"https:\/\/talkpal.ai\/zh-hans\/grammar_exercises\/temps-%e6%b3%95%e8%af%ad%e8%af%ad%e6%b3%95%e7%bb%83%e4%b9%a0\/\">temps<\/a> grammatical utilis\u00e9 pour d\u00e9crire des actions qui \u00e9taient en <a href=\"https:\/\/talkpal.ai\/courses\/\">cours<\/a> \u00e0 un moment pr\u00e9cis dans le pass\u00e9. Dans cet article, nous vous pr\u00e9senterons les r\u00e8gles, les usages et des exemples pour vous aider \u00e0 comprendre et ma\u00eetriser ce temps en anglais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Formation du Past Progressive<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le Past Progressive se compose de deux \u00e9l\u00e9ments : l&rsquo;auxiliaire \u00ab\u00a0<a href=\"https:\/\/talkpal.ai\/culture\/how-do-you-conjugate-the-verb-to-be-in-the-past-tense-in-somali\/\">to be<\/a>\u00a0\u00bb conjugu\u00e9 au <a href=\"https:\/\/talkpal.ai\/zh-hans\/grammar_exercises\/passe-simple-%e6%b3%95%e8%af%ad%e8%af%ad%e6%b3%95%e7%bb%83%e4%b9%a0\/\">pass\u00e9 simple<\/a> (was\/were) et la forme en -ing du verbe principal (base verbale + -ing).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">R\u00e8gles de conjugaison<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voici comment conjuguer le Past Progressive en fonction du sujet :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Je (I) : I was + verbe en -ing<\/li>\n\n\n\n<li>Tu (You) : You were + verbe en -ing<\/li>\n\n\n\n<li>Il\/elle\/on (He\/She\/It) : He\/She\/It was + verbe en -ing<\/li>\n\n\n\n<li>Nous (We) : We were + verbe en -ing<\/li>\n\n\n\n<li>Vous (You) : You were + verbe en -ing<\/li>\n\n\n\n<li>Ils\/elles (They) : They were + verbe en -ing<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">Exemples de conjugaison<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>I was reading a book. (Je lisais un livre.)<\/li>\n\n\n\n<li>You were playing soccer. (Tu jouais au football.)<\/li>\n\n\n\n<li>He was working on the project. (Il travaillait sur le projet.)<\/li>\n\n\n\n<li>We were watching a movie. (Nous regardions un film.)<\/li>\n\n\n\n<li>They were talking to each other. (Ils se parlaient.)<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Utilisation du Past Progressive<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le Past Progressive est g\u00e9n\u00e9ralement utilis\u00e9 pour d\u00e9crire des actions en cours \u00e0 un moment pr\u00e9cis dans le pass\u00e9. Voici les principaux cas d&rsquo;utilisation :<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Action en cours dans le pass\u00e9<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le Past Progressive d\u00e9crit une action qui \u00e9tait en cours \u00e0 un moment pr\u00e9cis dans le pass\u00e9. Par exemple :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>I was studying when the phone rang. (J&rsquo;\u00e9tudiais lorsque le t\u00e9l\u00e9phone a sonn\u00e9.)<\/li>\n\n\n\n<li>They were walking in the park when it started to rain. (Ils se promenaient dans le parc quand il a commenc\u00e9 \u00e0 pleuvoir.)<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">2. Deux actions simultan\u00e9es dans le pass\u00e9<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le Past Progressive peut \u00e9galement \u00eatre utilis\u00e9 pour d\u00e9crire deux actions qui se d\u00e9roulaient simultan\u00e9ment dans le pass\u00e9. Dans ce cas, les deux actions sont g\u00e9n\u00e9ralement exprim\u00e9es au Past Progressive. Par exemple :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>While I was cooking, my husband was setting the table. (Pendant que je cuisinais, mon mari mettait la table.)<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">3. Action interrompue par une autre action<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le Past Progressive est souvent utilis\u00e9 en combinaison avec le Past Simple pour indiquer qu&rsquo;une action en cours dans le pass\u00e9 a \u00e9t\u00e9 interrompue par une autre action. Dans ce cas, l&rsquo;action en cours est exprim\u00e9e au Past Progressive, tandis que l&rsquo;action qui interrompt est exprim\u00e9e au Past Simple. Par exemple :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>I was writing an email when the power went out. (J&rsquo;\u00e9crivais un e-mail lorsque le courant a coup\u00e9.)<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Questions et n\u00e9gations au Past Progressive<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Questions<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Pour poser une question au Past Progressive, il suffit d&rsquo;inverser l&rsquo;ordre de l&rsquo;auxiliaire \u00ab\u00a0to be\u00a0\u00bb et du sujet. Par exemple :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Were you watching TV when I called? (Regardais-tu la t\u00e9l\u00e9vision lorsque j&rsquo;ai appel\u00e9 ?)<\/li>\n\n\n\n<li>Was she working when the incident happened? (Travaillait-elle lorsque l&rsquo;incident s&rsquo;est produit ?)<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">N\u00e9gations<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Pour exprimer une action au Past Progressive \u00e0 la forme n\u00e9gative, il suffit d&rsquo;ajouter \u00ab\u00a0not\u00a0\u00bb apr\u00e8s l&rsquo;auxiliaire \u00ab\u00a0to be\u00a0\u00bb. Par exemple :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>I was not (wasn&rsquo;t) listening to music. (Je n&rsquo;\u00e9coutais pas de musique.)<\/li>\n\n\n\n<li>They were not (weren&rsquo;t) playing outside. (Ils ne jouaient pas dehors.)<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le Past Progressive est un temps important en anglais pour d\u00e9crire des actions en cours, simultan\u00e9es ou interrompues dans le pass\u00e9. En ma\u00eetrisant les r\u00e8gles de conjugaison, les usages et les exemples pr\u00e9sent\u00e9s dans cet article, vous serez en mesure d&rsquo;utiliser ce temps avec aisance et pr\u00e9cision.<\/p>\n","protected":false},"featured_media":1528142,"template":"","language":[383,388],"class_list":["post-10215","grammar","type-grammar","status-publish","has-post-thumbnail","hentry","language-anglais","language-temps-verbaux"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ma\u00eetriser le Past Progressive en anglais : Guide complet - Talkpal<\/title>\n<meta name=\"description\" content=\"Le Past Progressive, \u00e9galement connu sous le nom de &quot;Past Continuous&quot; en anglais, est un temps grammatical utilis\u00e9 pour d\u00e9crire des actions qui \u00e9taient en\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/talkpal.ai\/fr\/grammar\/maitriser-le-past-progressive-en-anglais-guide-complet\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ma\u00eetriser le Past Progressive en anglais : Guide complet\" \/>\n<meta property=\"og:description\" content=\"Le Past Progressive, \u00e9galement connu sous le nom de &quot;Past Continuous&quot; en anglais, est un temps grammatical utilis\u00e9 pour d\u00e9crire des actions qui \u00e9taient en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/talkpal.ai\/fr\/grammar\/maitriser-le-past-progressive-en-anglais-guide-complet\/\" \/>\n<meta property=\"og:site_name\" content=\"Talkpal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100090733639311\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-22T14:02:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/talkpal.ai\/wp-content\/uploads\/2023\/04\/TalkPal-Illustration-of-students-studying-grammar-lessons-108.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1456\" \/>\n\t<meta property=\"og:image:height\" content=\"816\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@talkpalai\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/grammar\\\/maitriser-le-past-progressive-en-anglais-guide-complet\\\/\",\"url\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/grammar\\\/maitriser-le-past-progressive-en-anglais-guide-complet\\\/\",\"name\":\"Ma\u00eetriser le Past Progressive en anglais : Guide complet - Talkpal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/grammar\\\/maitriser-le-past-progressive-en-anglais-guide-complet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/grammar\\\/maitriser-le-past-progressive-en-anglais-guide-complet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/talkpal.ai\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/trio-studies-on-balcony-learning-languages.webp\",\"datePublished\":\"2023-04-06T08:46:42+00:00\",\"dateModified\":\"2023-04-22T14:02:47+00:00\",\"description\":\"Le Past Progressive, \u00e9galement connu sous le nom de \\\"Past Continuous\\\" en anglais, est un temps grammatical utilis\u00e9 pour d\u00e9crire des actions qui \u00e9taient en\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/grammar\\\/maitriser-le-past-progressive-en-anglais-guide-complet\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/talkpal.ai\\\/fr\\\/grammar\\\/maitriser-le-past-progressive-en-anglais-guide-complet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/grammar\\\/maitriser-le-past-progressive-en-anglais-guide-complet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/talkpal.ai\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/trio-studies-on-balcony-learning-languages.webp\",\"contentUrl\":\"https:\\\/\\\/talkpal.ai\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/trio-studies-on-balcony-learning-languages.webp\",\"width\":1200,\"height\":896,\"caption\":\"Three people work on laptops at a balcony table while learning languages against a scenic mountain backdrop.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/grammar\\\/maitriser-le-past-progressive-en-anglais-guide-complet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anglais\",\"item\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/language\\\/anglais\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Temps - Grammaire anglaise\",\"item\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/language\\\/temps-verbaux\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ma\u00eetriser le Past Progressive en anglais : Guide complet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/\",\"name\":\"Talkpal\",\"description\":\"AI Language Learning\",\"publisher\":{\"@id\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/#organization\"},\"alternateName\":\"Talkpal AI\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/#organization\",\"name\":\"Talkpal, Inc.\",\"alternateName\":\"Talkpal AI\",\"url\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/talkpal.ai\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Talkpal-Logo-Icon.png\",\"contentUrl\":\"https:\\\/\\\/talkpal.ai\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Talkpal-Logo-Icon.png\",\"width\":2880,\"height\":2880,\"caption\":\"Talkpal, Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/talkpal.ai\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100090733639311\",\"https:\\\/\\\/x.com\\\/talkpalai\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/talkpal\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@TalkPal\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@talkpal\",\"https:\\\/\\\/www.instagram.com\\\/talkpal_ai\\\/\",\"https:\\\/\\\/www.crunchbase.com\\\/organization\\\/talkpal-9cde\",\"https:\\\/\\\/www.g2.com\\\/products\\\/talkpal-for-business\\\/\",\"https:\\\/\\\/www.trustpilot.com\\\/review\\\/talkpal.ai\",\"https:\\\/\\\/www.capterra.com\\\/p\\\/10006800\\\/TalkPal\\\/\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Talkpal_AI\"],\"description\":\"Talkpal is a language learning web and mobile education app, powered by the latest AI technologies, that provides engaging experiences to its customers in many different languages to help them improve their language skills. Users can chat about unlimited amount of topics with the app and use other modes to practice their language learning.\",\"email\":\"support@talkpal.ai\",\"legalName\":\"Talkpal, Inc.\",\"foundingDate\":\"2023-04-03\",\"duns\":\"118989042\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"publishingPrinciples\":\"https:\\\/\\\/talkpal.ai\\\/publishing-principles\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/talkpal.ai\\\/actionable-feedback-policy\\\/\",\"correctionsPolicy\":\"https:\\\/\\\/talkpal.ai\\\/corrections-policy\\\/\",\"ethicsPolicy\":\"https:\\\/\\\/talkpal.ai\\\/ethics-policy\\\/\",\"diversityPolicy\":\"https:\\\/\\\/talkpal.ai\\\/diversity-policy\\\/\",\"diversityStaffingReport\":\"https:\\\/\\\/talkpal.ai\\\/diversity-policy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ma\u00eetriser le Past Progressive en anglais : Guide complet - Talkpal","description":"Le Past Progressive, \u00e9galement connu sous le nom de \"Past Continuous\" en anglais, est un temps grammatical utilis\u00e9 pour d\u00e9crire des actions qui \u00e9taient en","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/talkpal.ai\/fr\/grammar\/maitriser-le-past-progressive-en-anglais-guide-complet\/","og_locale":"fr_FR","og_type":"article","og_title":"Ma\u00eetriser le Past Progressive en anglais : Guide complet","og_description":"Le Past Progressive, \u00e9galement connu sous le nom de \"Past Continuous\" en anglais, est un temps grammatical utilis\u00e9 pour d\u00e9crire des actions qui \u00e9taient en","og_url":"https:\/\/talkpal.ai\/fr\/grammar\/maitriser-le-past-progressive-en-anglais-guide-complet\/","og_site_name":"Talkpal","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100090733639311","article_modified_time":"2023-04-22T14:02:47+00:00","og_image":[{"width":1456,"height":816,"url":"https:\/\/talkpal.ai\/wp-content\/uploads\/2023\/04\/TalkPal-Illustration-of-students-studying-grammar-lessons-108.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@talkpalai","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/talkpal.ai\/fr\/grammar\/maitriser-le-past-progressive-en-anglais-guide-complet\/","url":"https:\/\/talkpal.ai\/fr\/grammar\/maitriser-le-past-progressive-en-anglais-guide-complet\/","name":"Ma\u00eetriser le Past Progressive en anglais : Guide complet - Talkpal","isPartOf":{"@id":"https:\/\/talkpal.ai\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/talkpal.ai\/fr\/grammar\/maitriser-le-past-progressive-en-anglais-guide-complet\/#primaryimage"},"image":{"@id":"https:\/\/talkpal.ai\/fr\/grammar\/maitriser-le-past-progressive-en-anglais-guide-complet\/#primaryimage"},"thumbnailUrl":"https:\/\/talkpal.ai\/wp-content\/uploads\/2025\/12\/trio-studies-on-balcony-learning-languages.webp","datePublished":"2023-04-06T08:46:42+00:00","dateModified":"2023-04-22T14:02:47+00:00","description":"Le Past Progressive, \u00e9galement connu sous le nom de \"Past Continuous\" en anglais, est un temps grammatical utilis\u00e9 pour d\u00e9crire des actions qui \u00e9taient en","breadcrumb":{"@id":"https:\/\/talkpal.ai\/fr\/grammar\/maitriser-le-past-progressive-en-anglais-guide-complet\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/talkpal.ai\/fr\/grammar\/maitriser-le-past-progressive-en-anglais-guide-complet\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/talkpal.ai\/fr\/grammar\/maitriser-le-past-progressive-en-anglais-guide-complet\/#primaryimage","url":"https:\/\/talkpal.ai\/wp-content\/uploads\/2025\/12\/trio-studies-on-balcony-learning-languages.webp","contentUrl":"https:\/\/talkpal.ai\/wp-content\/uploads\/2025\/12\/trio-studies-on-balcony-learning-languages.webp","width":1200,"height":896,"caption":"Three people work on laptops at a balcony table while learning languages against a scenic mountain backdrop."},{"@type":"BreadcrumbList","@id":"https:\/\/talkpal.ai\/fr\/grammar\/maitriser-le-past-progressive-en-anglais-guide-complet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/talkpal.ai\/fr\/"},{"@type":"ListItem","position":2,"name":"Anglais","item":"https:\/\/talkpal.ai\/fr\/language\/anglais\/"},{"@type":"ListItem","position":3,"name":"Temps - Grammaire anglaise","item":"https:\/\/talkpal.ai\/fr\/language\/temps-verbaux\/"},{"@type":"ListItem","position":4,"name":"Ma\u00eetriser le Past Progressive en anglais : Guide complet"}]},{"@type":"WebSite","@id":"https:\/\/talkpal.ai\/fr\/#website","url":"https:\/\/talkpal.ai\/fr\/","name":"Talkpal","description":"AI Language Learning","publisher":{"@id":"https:\/\/talkpal.ai\/fr\/#organization"},"alternateName":"Talkpal AI","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/talkpal.ai\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/talkpal.ai\/fr\/#organization","name":"Talkpal, Inc.","alternateName":"Talkpal AI","url":"https:\/\/talkpal.ai\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/talkpal.ai\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/talkpal.ai\/wp-content\/uploads\/2024\/03\/Talkpal-Logo-Icon.png","contentUrl":"https:\/\/talkpal.ai\/wp-content\/uploads\/2024\/03\/Talkpal-Logo-Icon.png","width":2880,"height":2880,"caption":"Talkpal, Inc."},"image":{"@id":"https:\/\/talkpal.ai\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100090733639311","https:\/\/x.com\/talkpalai","https:\/\/www.linkedin.com\/company\/talkpal\/","https:\/\/www.youtube.com\/@TalkPal\/","https:\/\/www.tiktok.com\/@talkpal","https:\/\/www.instagram.com\/talkpal_ai\/","https:\/\/www.crunchbase.com\/organization\/talkpal-9cde","https:\/\/www.g2.com\/products\/talkpal-for-business\/","https:\/\/www.trustpilot.com\/review\/talkpal.ai","https:\/\/www.capterra.com\/p\/10006800\/TalkPal\/","https:\/\/en.wikipedia.org\/wiki\/Talkpal_AI"],"description":"Talkpal is a language learning web and mobile education app, powered by the latest AI technologies, that provides engaging experiences to its customers in many different languages to help them improve their language skills. Users can chat about unlimited amount of topics with the app and use other modes to practice their language learning.","email":"support@talkpal.ai","legalName":"Talkpal, Inc.","foundingDate":"2023-04-03","duns":"118989042","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"publishingPrinciples":"https:\/\/talkpal.ai\/publishing-principles\/","actionableFeedbackPolicy":"https:\/\/talkpal.ai\/actionable-feedback-policy\/","correctionsPolicy":"https:\/\/talkpal.ai\/corrections-policy\/","ethicsPolicy":"https:\/\/talkpal.ai\/ethics-policy\/","diversityPolicy":"https:\/\/talkpal.ai\/diversity-policy\/","diversityStaffingReport":"https:\/\/talkpal.ai\/diversity-policy\/"}]}},"_links":{"self":[{"href":"https:\/\/talkpal.ai\/fr\/wp-json\/wp\/v2\/grammar\/10215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/talkpal.ai\/fr\/wp-json\/wp\/v2\/grammar"}],"about":[{"href":"https:\/\/talkpal.ai\/fr\/wp-json\/wp\/v2\/types\/grammar"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/talkpal.ai\/fr\/wp-json\/wp\/v2\/media\/1528142"}],"wp:attachment":[{"href":"https:\/\/talkpal.ai\/fr\/wp-json\/wp\/v2\/media?parent=10215"}],"wp:term":[{"taxonomy":"language","embeddable":true,"href":"https:\/\/talkpal.ai\/fr\/wp-json\/wp\/v2\/language?post=10215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}